{"id":8401,"date":"2025-11-06T22:51:32","date_gmt":"2025-11-06T22:51:04","guid":{"rendered":"https:\/\/therotellagroup.org\/gww\/index.php\/armored-combat-6\/"},"modified":"2025-11-07T16:48:40","modified_gmt":"2025-11-07T16:48:40","slug":"armored-combat-6","status":"publish","type":"page","link":"https:\/\/therotellagroup.org\/gww\/index.php\/war\/war-activities\/events-2\/armored-combat-6\/","title":{"rendered":"Hounds"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8401\" class=\"elementor elementor-8401\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f984513 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f984513\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e032a1d\" data-id=\"e032a1d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47d8f8b elementor-widget elementor-widget-heading\" data-id=\"47d8f8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hounds<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d82a93 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"8d82a93\" data-element_type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-8d82a93\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-487\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/gate-info\/\" class=\"elementor-item menu-link\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-7946\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/\" class=\"elementor-item menu-link\">ABOUT<span role=\"presentation\" class=\"dropdown-menu-toggle\" ><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7958\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/from-the-stewards\/\" class=\"elementor-sub-item menu-link\">FROM THE STEWARDS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7957\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/from-their-majesties\/\" class=\"elementor-sub-item menu-link\">FROM THEIR MAJESTIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7956\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/from-their-highnesses\/\" class=\"elementor-sub-item menu-link\">FROM THEIR HIGHNESSES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7955\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/visiting-royals\/\" class=\"elementor-sub-item menu-link\">VISITING ROYALS<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-488\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/camp-info\/\" class=\"elementor-item menu-link\">CAMP INFO<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-489\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/war-activities\/events-2\/\" class=\"elementor-item menu-link\">ACTIVITIES<span role=\"presentation\" class=\"dropdown-menu-toggle\" ><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8604\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities\/\" class=\"elementor-sub-item menu-link\">TUESDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8602\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-2\/\" class=\"elementor-sub-item menu-link\">WEDNESDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8601\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-3\/\" class=\"elementor-sub-item menu-link\">THURSDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8600\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-4\/\" class=\"elementor-sub-item menu-link\">FRIDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8599\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-5\/\" class=\"elementor-sub-item menu-link\">SATURDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8603\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-6\/\" class=\"elementor-sub-item menu-link\">SUNDAY\u2019S ACTIVITIES<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-490\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/merchants\/\" class=\"elementor-item menu-link\">MERCHANTS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7603\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/pre-reg\/pre-reg-other\/volunteering\/\" class=\"elementor-item menu-link\">VOLUNTEERING<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3653\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/staff\/z-staff\/\" class=\"elementor-item menu-link\">STAFF<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8d82a93\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-487\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/gate-info\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-7946\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">ABOUT<span role=\"presentation\" class=\"dropdown-menu-toggle\" ><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7958\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/from-the-stewards\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">FROM THE STEWARDS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7957\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/from-their-majesties\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">FROM THEIR MAJESTIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7956\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/from-their-highnesses\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">FROM THEIR HIGHNESSES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7955\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/about\/visiting-royals\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">VISITING ROYALS<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-488\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/camp-info\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">CAMP INFO<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-489\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/war-activities\/events-2\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">ACTIVITIES<span role=\"presentation\" class=\"dropdown-menu-toggle\" ><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8604\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">TUESDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8602\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-2\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">WEDNESDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8601\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-3\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">THURSDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8600\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-4\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">FRIDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8599\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-5\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">SATURDAY&#8217;S ACTIVITIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8603\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/mondays-activities-6\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">SUNDAY\u2019S ACTIVITIES<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-490\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/merchants\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">MERCHANTS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7603\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/pre-reg\/pre-reg-other\/volunteering\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">VOLUNTEERING<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3653\"><a href=\"https:\/\/therotellagroup.org\/gww\/index.php\/war\/staff\/z-staff\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">STAFF<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4ad520 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4ad520\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6179e84\" data-id=\"6179e84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20877df elementor-widget elementor-widget-image\" data-id=\"20877df\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"940\" height=\"1222\" src=\"https:\/\/therotellagroup.org\/gww\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-06-at-6.07.37-PM.png\" class=\"attachment-full size-full wp-image-8481\" alt=\"\" srcset=\"https:\/\/therotellagroup.org\/gww\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-06-at-6.07.37-PM.png 940w, https:\/\/therotellagroup.org\/gww\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-06-at-6.07.37-PM-231x300.png 231w, https:\/\/therotellagroup.org\/gww\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-06-at-6.07.37-PM-788x1024.png 788w, https:\/\/therotellagroup.org\/gww\/wp-content\/uploads\/2025\/11\/Screenshot-2025-11-06-at-6.07.37-PM-768x998.png 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hounds<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":469,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-8401","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/pages\/8401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/comments?post=8401"}],"version-history":[{"count":10,"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/pages\/8401\/revisions"}],"predecessor-version":[{"id":8569,"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/pages\/8401\/revisions\/8569"}],"up":[{"embeddable":true,"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/pages\/469"}],"wp:attachment":[{"href":"https:\/\/therotellagroup.org\/gww\/index.php\/wp-json\/wp\/v2\/media?parent=8401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}